{"id":721,"count":0,"description":"","link":"https:\/\/www.snowtrex.cz\/magazin\/tag\/monguelfo-tesido\/","name":"Monguelfo-Tesido","slug":"monguelfo-tesido","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Monguelfo-Tesido - SnowTrex Ski-Magaz\u00edn<\/title>\n<meta name=\"description\" content=\"Monguelfo-Tesido - SnowTrex Ski-Magaz\u00edn\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monguelfo-Tesido\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.snowtrex.cz\/magazin\/tag\/monguelfo-tesido\/\" \/>\n<meta property=\"og:site_name\" content=\"SnowTrex Ski-Magaz\u00edn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.cz\\\/tag\\\/monguelfo-tesido\\\/\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.cz\\\/tag\\\/monguelfo-tesido\\\/\",\"name\":\"Monguelfo-Tesido - SnowTrex Ski-Magaz\u00edn\",\"description\":\"Monguelfo-Tesido - SnowTrex Ski-Magaz\u00edn\",\"inLanguage\":\"cs\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.cz\\\/#website\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.cz\\\/\",\"name\":\"SnowTrex Ski-Magaz\u00edn\",\"description\":\"V\u0161e o ly\u017eov\u00e1n\u00ed, snowboardingu a zimn\u00ed dovolen\u00e9!\",\"publisher\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.cz\\\/#organization\"},\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.cz\\\/#organization\",\"name\":\"TravelTrex GmbH\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.cz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.cz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/blog.snowtrex.com\\\/cz-magazin\\\/files\\\/2025\\\/09\\\/TravelTrex-Logo_RGB_transp.png\",\"contentUrl\":\"http:\\\/\\\/blog.snowtrex.com\\\/cz-magazin\\\/files\\\/2025\\\/09\\\/TravelTrex-Logo_RGB_transp.png\",\"width\":1080,\"height\":282,\"caption\":\"TravelTrex GmbH\"},\"image\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.cz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/snowtrex\",\"https:\\\/\\\/www.instagram.com\\\/snowtrex_ski\"],\"description\":\"Od roku 1999 je SnowTrex p\u0159edn\u00edm n\u011bmeck\u00fdm cestovn\u00edm kancel\u00e1\u0159\u00edm pro ly\u017ea\u0159sk\u00e9 dovolen\u00e9. Spole\u010dnost nab\u00edz\u00ed sv\u00e9 slu\u017eby ve 13 jazyc\u00edch a ka\u017edoro\u010dn\u011b doprav\u00ed v\u00edce ne\u017e 100 000 host\u016f do obl\u00edben\u00fdch destinac\u00ed, jako je Rakousko, Francie, It\u00e1lie, \u0160v\u00fdcarsko a N\u011bmecko.\",\"email\":\"info-cz@snowtrex.com\",\"telephone\":\"234 495 495\",\"legalName\":\"TravelTrex GmbH\",\"foundingDate\":\"1999-07-01\",\"vatID\":\"DE 813 076 768\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Monguelfo-Tesido - SnowTrex Ski-Magaz\u00edn","description":"Monguelfo-Tesido - SnowTrex Ski-Magaz\u00edn","robots":{"index":"noindex","follow":"follow"},"og_locale":"cs_CZ","og_type":"article","og_title":"Monguelfo-Tesido","og_url":"https:\/\/www.snowtrex.cz\/magazin\/tag\/monguelfo-tesido\/","og_site_name":"SnowTrex Ski-Magaz\u00edn","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.snowtrex.cz\/magazin\/tag\/monguelfo-tesido\/","url":"https:\/\/www.snowtrex.cz\/magazin\/tag\/monguelfo-tesido\/","name":"Monguelfo-Tesido - SnowTrex Ski-Magaz\u00edn","description":"Monguelfo-Tesido - SnowTrex Ski-Magaz\u00edn","inLanguage":"cs"},{"@type":"WebSite","@id":"https:\/\/www.snowtrex.cz\/magazin\/#website","url":"https:\/\/www.snowtrex.cz\/magazin\/","name":"SnowTrex Ski-Magaz\u00edn","description":"V\u0161e o ly\u017eov\u00e1n\u00ed, snowboardingu a zimn\u00ed dovolen\u00e9!","publisher":{"@id":"https:\/\/www.snowtrex.cz\/magazin\/#organization"},"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/www.snowtrex.cz\/magazin\/#organization","name":"TravelTrex GmbH","url":"https:\/\/www.snowtrex.cz\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/www.snowtrex.cz\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.snowtrex.cz\/magazin\/files\/2025\/09\/TravelTrex-Logo_RGB_transp.png","contentUrl":"https:\/\/www.snowtrex.cz\/magazin\/files\/2025\/09\/TravelTrex-Logo_RGB_transp.png","width":1080,"height":282,"caption":"TravelTrex GmbH"},"image":{"@id":"https:\/\/www.snowtrex.cz\/magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/snowtrex","https:\/\/www.instagram.com\/snowtrex_ski"],"description":"Od roku 1999 je SnowTrex p\u0159edn\u00edm n\u011bmeck\u00fdm cestovn\u00edm kancel\u00e1\u0159\u00edm pro ly\u017ea\u0159sk\u00e9 dovolen\u00e9. Spole\u010dnost nab\u00edz\u00ed sv\u00e9 slu\u017eby ve 13 jazyc\u00edch a ka\u017edoro\u010dn\u011b doprav\u00ed v\u00edce ne\u017e 100 000 host\u016f do obl\u00edben\u00fdch destinac\u00ed, jako je Rakousko, Francie, It\u00e1lie, \u0160v\u00fdcarsko a N\u011bmecko.","email":"info-cz@snowtrex.com","telephone":"234 495 495","legalName":"TravelTrex GmbH","foundingDate":"1999-07-01","vatID":"DE 813 076 768","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/www.snowtrex.cz\/magazin\/wp-json\/wp\/v2\/tags\/721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snowtrex.cz\/magazin\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.snowtrex.cz\/magazin\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.snowtrex.cz\/magazin\/wp-json\/wp\/v2\/posts?tags=721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}